{"id":7292,"date":"2018-03-09T17:20:18","date_gmt":"2018-03-09T16:20:18","guid":{"rendered":"https:\/\/aedic.eu\/?p=7292"},"modified":"2018-03-09T17:20:18","modified_gmt":"2018-03-09T16:20:18","slug":"banque-des-etats-de-lafrique-centrale-beac","status":"publish","type":"post","link":"https:\/\/aedic.eu\/fr\/economie\/banque-des-etats-de-lafrique-centrale-beac\/","title":{"rendered":"BANQUE DES ETATS DE L'AFRIQUE CENTRALE - BEAC"},"content":{"rendered":"<h2>BEAC (Banque des \u00c9tats de l'Afrique centrale - BCAS).<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2849 alignleft\" src=\"https:\/\/aedic.eu\/wp-content\/uploads\/2018\/07\/beac-banca-centrale-del-camerun-300x150.jpg\" alt=\"beac banque centrale du cameroun\" width=\"300\" height=\"150\" title=\"\">Elle est issue de la Banque Centrale des Etats de l'Afrique Equatoriale et du Cameroun (BCEAEC), elle-m\u00eame issue en 1959 de la r\u00e9organisation de l'Institut d'Emission de l'Afrique Equatoriale Fran\u00e7aise et du Cameroun.<\/p>\n<p>La transformation du BCEAEC en <strong>BEAC<\/strong> a eu lieu \u00e0 la suite de la conclusion d'un nouvel accord de coop\u00e9ration mon\u00e9taire avec la France par cinq pays le 23.11.1972 :<\/p>\n<ul>\n<li>Cameroun,<\/li>\n<li>R\u00e9publique centrafricaine,<\/li>\n<li>Tchad,<\/li>\n<li>R\u00e9publique du Congo<\/li>\n<li>Gabon<\/li>\n<\/ul>\n<p>auxquels la Guin\u00e9e \u00e9quatoriale a \u00e9t\u00e9 ajout\u00e9e le 1.1.1985 et qui forment une union mon\u00e9taire, l'UMAC.<\/p>\n<p><a href=\"https:\/\/aedic.eu\/fr\/zone-del-franco\/\"><strong>Les six pays qui font partie de la zone franc<\/strong><\/a> (q.v. pour les effets du passage \u00e0 l'euro) et la <strong>BEAC<\/strong> <strong>est l'institut d'\u00e9mission du franc CFA, une monnaie l\u00e9gale r\u00e9gionale librement convertible en francs fran\u00e7ais et, depuis le 1.1.1999, en euros. <\/strong><\/p>\n<p><strong>La Banque est bas\u00e9e \u00e0 Yoaund\u00e9 (Cameroun).<\/strong> et est dirig\u00e9e par un gouverneur et un directoire de 13 membres, dont 10 sont d\u00e9sign\u00e9s par les six \u00c9tats membres et trois par la France.<\/p>\n<p>La Banque a exerc\u00e9 un contr\u00f4le bancaire jusqu'en 1992. Cette ann\u00e9e-l\u00e0, le bureau a \u00e9t\u00e9 dissous et transform\u00e9 en une Commission bancaire autonome de l'Afrique centrale (COBAC), avec effet au 22 d\u00e9cembre 1992, charg\u00e9e d'\u00e9laborer la r\u00e9glementation et la supervision bancaires.<\/p>\n<p>La COBAC est pr\u00e9sid\u00e9e par le Gouverneur de la BEAC tandis que le Secr\u00e9taire G\u00e9n\u00e9ral est nomm\u00e9 par le Conseil des Ministres de l'UE. <a href=\"https:\/\/aedic.eu\/fr\/cemac\/\"><strong>CEMAC<\/strong><\/a> (Communaut\u00e9 \u00c9conomique et Mon\u00e9taire de l'Afrique Centrale).<\/p>","protected":false},"excerpt":{"rendered":"<p>BEAC (Banque des Etats de l'Afrique Centrale - BCAS). Elle est issue de la Banque Centrale des Etats de l'Afrique Equatoriale et du Cameroun (BCEAEC), elle-m\u00eame issue en 1959 de la r\u00e9organisation de l'Institut d'Emission de l'Afrique Equatoriale Fran\u00e7aise et du Cameroun. La transformation de la BCEAEC en BEAC a eu lieu en ... <\/p>\n<p class=\"read-more-container\"><a title=\"BANQUE DES ETATS DE L&#039;AFRIQUE CENTRALE - BEAC\" class=\"read-more button\" href=\"https:\/\/aedic.eu\/fr\/economie\/banque-des-etats-de-lafrique-centrale-beac\/#more-7292\" aria-label=\"Plus sur BANQUE DES ETATS DE L&#039;AFRIQUE CENTRALE - BEAC\">Lire plus<\/a><\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":158,"footnotes":""},"categories":[22],"tags":[60,67,87,101],"acf":[],"_links":{"self":[{"href":"https:\/\/aedic.eu\/fr\/wp-json\/wp\/v2\/posts\/7292"}],"collection":[{"href":"https:\/\/aedic.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aedic.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aedic.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aedic.eu\/fr\/wp-json\/wp\/v2\/comments?post=7292"}],"version-history":[{"count":0,"href":"https:\/\/aedic.eu\/fr\/wp-json\/wp\/v2\/posts\/7292\/revisions"}],"wp:attachment":[{"href":"https:\/\/aedic.eu\/fr\/wp-json\/wp\/v2\/media?parent=7292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aedic.eu\/fr\/wp-json\/wp\/v2\/categories?post=7292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aedic.eu\/fr\/wp-json\/wp\/v2\/tags?post=7292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}